{"id":13,"count":0,"description":"","link":"https:\/\/lavalen.co.id\/en\/category\/face\/","name":"Face","slug":"face","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Face Arsip - Lavalen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lavalen.co.id\/en\/category\/face\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Face Arsip - Lavalen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lavalen.co.id\/en\/category\/face\/\" \/>\n<meta property=\"og:site_name\" content=\"Lavalen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/lavalen.co.id\/category\/face\/\",\"url\":\"https:\/\/lavalen.co.id\/category\/face\/\",\"name\":\"Face Arsip - Lavalen\",\"isPartOf\":{\"@id\":\"https:\/\/lavalen.co.id\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/lavalen.co.id\/category\/face\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lavalen.co.id\/category\/face\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Beranda\",\"item\":\"https:\/\/lavalen.co.id\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Face\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lavalen.co.id\/#website\",\"url\":\"https:\/\/lavalen.co.id\/\",\"name\":\"Lavalen Beauty Center\",\"description\":\"Klinik Kecantikan dan Pelangsingan Terbaik\",\"publisher\":{\"@id\":\"https:\/\/lavalen.co.id\/#organization\"},\"alternateName\":\"LAVALEN BEAUTY CENTER\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lavalen.co.id\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lavalen.co.id\/#organization\",\"name\":\"Lavalen Beauty Center\",\"url\":\"https:\/\/lavalen.co.id\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lavalen.co.id\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lavalen.co.id\/wp-content\/uploads\/2025\/11\/logo-Lavelen-registered-01.png\",\"contentUrl\":\"https:\/\/lavalen.co.id\/wp-content\/uploads\/2025\/11\/logo-Lavelen-registered-01.png\",\"width\":1667,\"height\":1667,\"caption\":\"Lavalen Beauty Center\"},\"image\":{\"@id\":\"https:\/\/lavalen.co.id\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lavalen.co\",\"https:\/\/www.instagram.com\/lavalen.co\",\"https:\/\/www.youtube.com\/@lavalenskinbodyhairaesthet5494\",\"https:\/\/www.tiktok.com\/@lavalenclinic\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Face Arsip - Lavalen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lavalen.co.id\/en\/category\/face\/","og_locale":"en_US","og_type":"article","og_title":"Face Arsip - Lavalen","og_url":"https:\/\/lavalen.co.id\/en\/category\/face\/","og_site_name":"Lavalen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lavalen.co.id\/category\/face\/","url":"https:\/\/lavalen.co.id\/category\/face\/","name":"Face Arsip - Lavalen","isPartOf":{"@id":"https:\/\/lavalen.co.id\/#website"},"breadcrumb":{"@id":"https:\/\/lavalen.co.id\/category\/face\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lavalen.co.id\/category\/face\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Beranda","item":"https:\/\/lavalen.co.id\/"},{"@type":"ListItem","position":2,"name":"Face"}]},{"@type":"WebSite","@id":"https:\/\/lavalen.co.id\/#website","url":"https:\/\/lavalen.co.id\/","name":"Lavalen Beauty Center","description":"Best Beauty and Slimming Clinic","publisher":{"@id":"https:\/\/lavalen.co.id\/#organization"},"alternateName":"LAVALEN BEAUTY CENTER","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lavalen.co.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lavalen.co.id\/#organization","name":"Lavalen Beauty Center","url":"https:\/\/lavalen.co.id\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lavalen.co.id\/#\/schema\/logo\/image\/","url":"https:\/\/lavalen.co.id\/wp-content\/uploads\/2025\/11\/logo-Lavelen-registered-01.png","contentUrl":"https:\/\/lavalen.co.id\/wp-content\/uploads\/2025\/11\/logo-Lavelen-registered-01.png","width":1667,"height":1667,"caption":"Lavalen Beauty Center"},"image":{"@id":"https:\/\/lavalen.co.id\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lavalen.co","https:\/\/www.instagram.com\/lavalen.co","https:\/\/www.youtube.com\/@lavalenskinbodyhairaesthet5494","https:\/\/www.tiktok.com\/@lavalenclinic"]}]}},"_links":{"self":[{"href":"https:\/\/lavalen.co.id\/en\/wp-json\/wp\/v2\/categories\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavalen.co.id\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lavalen.co.id\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lavalen.co.id\/en\/wp-json\/wp\/v2\/posts?categories=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}